{"id":612,"date":"2024-12-23T11:28:14","date_gmt":"2024-12-23T11:28:14","guid":{"rendered":"https:\/\/cwsdelhi.co.in\/naturegold\/?post_type=tool&#038;p=612"},"modified":"2025-03-12T09:53:57","modified_gmt":"2025-03-12T09:53:57","slug":"trowler-garden-tool-ng-ght-125","status":"publish","type":"tool","link":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/trowler-garden-tool-ng-ght-125\/","title":{"rendered":"Handtool NG-GHT-125"},"content":{"rendered":"<p>A multipurpose cultivator is a versatile gardening tool used for various tasks like tilling soil, removing weeds, and a erating the ground. It helps prepare garden beds, break up compacted soil, and improve soil structure for planting<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A multipurpose cultivator is a versatile gardening tool used for various tasks like tilling soil, removing weeds, and a erating [&hellip;]<\/p>\n","protected":false},"featured_media":2619,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"categories":[8],"class_list":["post-612","tool","type-tool","status-publish","has-post-thumbnail","hentry","category-hand-tools"],"acf":{"photo_gallery":{"gallery":[[{"id":619,"title":"DSC_0750","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0750.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0750-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0750-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0750-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0750-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0750.jpg 1500w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0750-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0750-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0750-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0750.jpg 1500w","media_details":{"width":1500,"height":1000,"sizes":{"medium":{"file":"DSC_0750-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":21071,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0750-300x200.jpg"},"large":{"file":"DSC_0750-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":185703,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0750-1024x683.jpg"},"thumbnail":{"file":"DSC_0750-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8633,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0750-150x150.jpg"},"medium_large":{"file":"DSC_0750-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":113242,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0750-768x512.jpg"}}},"alt_text":"","url":"","target":""},{"id":618,"title":"DSC_0749","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0749.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0749-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0749-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0749-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0749-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0749.jpg 1500w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0749-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0749-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0749-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0749.jpg 1500w","media_details":{"width":1500,"height":1000,"sizes":{"medium":{"file":"DSC_0749-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":21830,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0749-300x200.jpg"},"large":{"file":"DSC_0749-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":189784,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0749-1024x683.jpg"},"thumbnail":{"file":"DSC_0749-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8689,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0749-150x150.jpg"},"medium_large":{"file":"DSC_0749-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":115807,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0749-768x512.jpg"}}},"alt_text":"","url":"","target":""},{"id":617,"title":"DSC_0748","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0748.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0748-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0748-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0748-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0748-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0748.jpg 1500w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0748-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0748-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0748-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0748.jpg 1500w","media_details":{"width":1500,"height":1000,"sizes":{"medium":{"file":"DSC_0748-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":20073,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0748-300x200.jpg"},"large":{"file":"DSC_0748-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":157748,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0748-1024x683.jpg"},"thumbnail":{"file":"DSC_0748-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8346,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0748-150x150.jpg"},"medium_large":{"file":"DSC_0748-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":98572,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0748-768x512.jpg"}}},"alt_text":"","url":"","target":""},{"id":616,"title":"DSC_0747","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0747.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0747-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0747-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0747-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0747-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0747.jpg 1500w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0747-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0747-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0747-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0747.jpg 1500w","media_details":{"width":1500,"height":1000,"sizes":{"medium":{"file":"DSC_0747-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":19900,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0747-300x200.jpg"},"large":{"file":"DSC_0747-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":155426,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0747-1024x683.jpg"},"thumbnail":{"file":"DSC_0747-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8311,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0747-150x150.jpg"},"medium_large":{"file":"DSC_0747-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":97318,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0747-768x512.jpg"}}},"alt_text":"","url":"","target":""},{"id":615,"title":"DSC_0685","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0685.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0685-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0685-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0685-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0685-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0685.jpg 1500w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0685-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0685-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0685-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0685.jpg 1500w","media_details":{"width":1500,"height":1000,"sizes":{"medium":{"file":"DSC_0685-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":19024,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0685-300x200.jpg"},"large":{"file":"DSC_0685-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":140246,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0685-1024x683.jpg"},"thumbnail":{"file":"DSC_0685-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8296,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0685-150x150.jpg"},"medium_large":{"file":"DSC_0685-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":87843,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0685-768x512.jpg"}}},"alt_text":"","url":"","target":""},{"id":614,"title":"DSC_0670","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0670.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0670-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0670-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0670-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0670-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0670.jpg 1500w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0670-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0670-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0670-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0670.jpg 1500w","media_details":{"width":1500,"height":1000,"sizes":{"medium":{"file":"DSC_0670-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":18633,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0670-300x200.jpg"},"large":{"file":"DSC_0670-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":133942,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0670-1024x683.jpg"},"thumbnail":{"file":"DSC_0670-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8263,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0670-150x150.jpg"},"medium_large":{"file":"DSC_0670-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":84315,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/DSC_0670-768x512.jpg"}}},"alt_text":"","url":"","target":""}]]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Handtool NG-GHT-125 - Nature Gold<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/trowler-garden-tool-ng-ght-125\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Handtool NG-GHT-125 - Nature Gold\" \/>\n<meta property=\"og:description\" content=\"A multipurpose cultivator is a versatile gardening tool used for various tasks like tilling soil, removing weeds, and a erating [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/trowler-garden-tool-ng-ght-125\/\" \/>\n<meta property=\"og:site_name\" content=\"Nature Gold\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-12T09:53:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/Trowler.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/trowler-garden-tool-ng-ght-125\\\/\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/trowler-garden-tool-ng-ght-125\\\/\",\"name\":\"Handtool NG-GHT-125 - Nature Gold\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/trowler-garden-tool-ng-ght-125\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/trowler-garden-tool-ng-ght-125\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Trowler.webp\",\"datePublished\":\"2024-12-23T11:28:14+00:00\",\"dateModified\":\"2025-03-12T09:53:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/trowler-garden-tool-ng-ght-125\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/trowler-garden-tool-ng-ght-125\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/trowler-garden-tool-ng-ght-125\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Trowler.webp\",\"contentUrl\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Trowler.webp\",\"width\":1000,\"height\":1000,\"caption\":\"Trowler\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/trowler-garden-tool-ng-ght-125\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Handtool NG-GHT-125\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#website\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/\",\"name\":\"Nature Gold\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#organization\",\"name\":\"Nature Gold\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/nature_gold1.png\",\"contentUrl\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/nature_gold1.png\",\"width\":546,\"height\":246,\"caption\":\"Nature Gold\"},\"image\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Handtool NG-GHT-125 - Nature Gold","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/trowler-garden-tool-ng-ght-125\/","og_locale":"en_US","og_type":"article","og_title":"Handtool NG-GHT-125 - Nature Gold","og_description":"A multipurpose cultivator is a versatile gardening tool used for various tasks like tilling soil, removing weeds, and a erating [&hellip;]","og_url":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/trowler-garden-tool-ng-ght-125\/","og_site_name":"Nature Gold","article_modified_time":"2025-03-12T09:53:57+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/Trowler.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/trowler-garden-tool-ng-ght-125\/","url":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/trowler-garden-tool-ng-ght-125\/","name":"Handtool NG-GHT-125 - Nature Gold","isPartOf":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/trowler-garden-tool-ng-ght-125\/#primaryimage"},"image":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/trowler-garden-tool-ng-ght-125\/#primaryimage"},"thumbnailUrl":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/Trowler.webp","datePublished":"2024-12-23T11:28:14+00:00","dateModified":"2025-03-12T09:53:57+00:00","breadcrumb":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/trowler-garden-tool-ng-ght-125\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cwsdelhi.co.in\/naturegold\/tool\/trowler-garden-tool-ng-ght-125\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/trowler-garden-tool-ng-ght-125\/#primaryimage","url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/Trowler.webp","contentUrl":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/12\/Trowler.webp","width":1000,"height":1000,"caption":"Trowler"},{"@type":"BreadcrumbList","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/trowler-garden-tool-ng-ght-125\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cwsdelhi.co.in\/naturegold\/"},{"@type":"ListItem","position":2,"name":"Handtool NG-GHT-125"}]},{"@type":"WebSite","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#website","url":"https:\/\/cwsdelhi.co.in\/naturegold\/","name":"Nature Gold","description":"","publisher":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cwsdelhi.co.in\/naturegold\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#organization","name":"Nature Gold","url":"https:\/\/cwsdelhi.co.in\/naturegold\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#\/schema\/logo\/image\/","url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/11\/nature_gold1.png","contentUrl":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/11\/nature_gold1.png","width":546,"height":246,"caption":"Nature Gold"},"image":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool\/612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool"}],"about":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/types\/tool"}],"version-history":[{"count":2,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool\/612\/revisions"}],"predecessor-version":[{"id":2703,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool\/612\/revisions\/2703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/media\/2619"}],"wp:attachment":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/media?parent=612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/categories?post=612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}