{"id":2118,"date":"2025-02-20T07:37:52","date_gmt":"2025-02-20T07:37:52","guid":{"rendered":"https:\/\/cwsdelhi.co.in\/naturegold\/?post_type=tool&#038;p=2118"},"modified":"2025-03-11T09:13:22","modified_gmt":"2025-03-11T09:13:22","slug":"ng-200d-blue-white","status":"publish","type":"tool","link":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-200d-blue-white\/","title":{"rendered":"NG-200D (Blue &#038; White)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2119,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"categories":[17],"class_list":["post-2118","tool","type-tool","status-publish","has-post-thumbnail","hentry","category-trigger-sprayer"],"acf":{"photo_gallery":{"gallery":[[{"id":2122,"title":"Untitled-1","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/Untitled-1-5.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/Untitled-1-5-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/Untitled-1-5.jpg 750w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/Untitled-1-5-300x300.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/Untitled-1-5-150x150.jpg 150w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/Untitled-1-5-300x300.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/Untitled-1-5-150x150.jpg 150w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/Untitled-1-5.jpg 750w","media_details":{"width":750,"height":750,"sizes":{"medium":{"file":"Untitled-1-5-300x300.jpg","width":300,"height":300,"mime-type":"image\/jpeg","filesize":2721,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/Untitled-1-5-300x300.jpg"},"thumbnail":{"file":"Untitled-1-5-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":1268,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/Untitled-1-5-150x150.jpg"}}},"alt_text":"","url":"","target":""},{"id":2121,"title":"DSC_0499","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0499.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0499-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0499-683x1024.jpg 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0499-200x300.jpg 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0499-768x1152.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0499.jpg 1000w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0499-200x300.jpg 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0499-683x1024.jpg 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0499-768x1152.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0499.jpg 1000w","media_details":{"width":1000,"height":1500,"sizes":{"medium":{"file":"DSC_0499-200x300.jpg","width":200,"height":300,"mime-type":"image\/jpeg","filesize":24798,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0499-200x300.jpg"},"large":{"file":"DSC_0499-683x1024.jpg","width":683,"height":1024,"mime-type":"image\/jpeg","filesize":171913,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0499-683x1024.jpg"},"thumbnail":{"file":"DSC_0499-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":10416,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0499-150x150.jpg"},"medium_large":{"file":"DSC_0499-768x1152.jpg","width":768,"height":1152,"mime-type":"image\/jpeg","filesize":203813,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0499-768x1152.jpg"}}},"alt_text":"","url":"","target":""},{"id":2120,"title":"DSC_0496","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0496.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0496-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0496-683x1024.jpg 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0496-200x300.jpg 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0496-768x1152.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0496.jpg 1000w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0496-200x300.jpg 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0496-683x1024.jpg 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0496-768x1152.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0496.jpg 1000w","media_details":{"width":1000,"height":1500,"sizes":{"medium":{"file":"DSC_0496-200x300.jpg","width":200,"height":300,"mime-type":"image\/jpeg","filesize":24410,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0496-200x300.jpg"},"large":{"file":"DSC_0496-683x1024.jpg","width":683,"height":1024,"mime-type":"image\/jpeg","filesize":172571,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0496-683x1024.jpg"},"thumbnail":{"file":"DSC_0496-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":10250,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0496-150x150.jpg"},"medium_large":{"file":"DSC_0496-768x1152.jpg","width":768,"height":1152,"mime-type":"image\/jpeg","filesize":204926,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/DSC_0496-768x1152.jpg"}}},"alt_text":"","url":"","target":""}]]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NG-200D (Blue &amp; White) - Nature Gold<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-200d-blue-white\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NG-200D (Blue &amp; White) - Nature Gold\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-200d-blue-white\/\" \/>\n<meta property=\"og:site_name\" content=\"Nature Gold\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-11T09:13:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/200-d-blue-white.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1250\" \/>\n\t<meta property=\"og:image:height\" content=\"1250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-200d-blue-white\\\/\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-200d-blue-white\\\/\",\"name\":\"NG-200D (Blue & White) - Nature Gold\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-200d-blue-white\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-200d-blue-white\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/200-d-blue-white.jpg\",\"datePublished\":\"2025-02-20T07:37:52+00:00\",\"dateModified\":\"2025-03-11T09:13:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-200d-blue-white\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-200d-blue-white\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-200d-blue-white\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/200-d-blue-white.jpg\",\"contentUrl\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/200-d-blue-white.jpg\",\"width\":1250,\"height\":1250,\"caption\":\"Blue & White\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-200d-blue-white\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NG-200D (Blue &#038; White)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#website\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/\",\"name\":\"Nature Gold\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#organization\",\"name\":\"Nature Gold\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/nature_gold1.png\",\"contentUrl\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/nature_gold1.png\",\"width\":546,\"height\":246,\"caption\":\"Nature Gold\"},\"image\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NG-200D (Blue & White) - Nature Gold","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-200d-blue-white\/","og_locale":"en_US","og_type":"article","og_title":"NG-200D (Blue & White) - Nature Gold","og_url":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-200d-blue-white\/","og_site_name":"Nature Gold","article_modified_time":"2025-03-11T09:13:22+00:00","og_image":[{"width":1250,"height":1250,"url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/200-d-blue-white.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-200d-blue-white\/","url":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-200d-blue-white\/","name":"NG-200D (Blue & White) - Nature Gold","isPartOf":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-200d-blue-white\/#primaryimage"},"image":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-200d-blue-white\/#primaryimage"},"thumbnailUrl":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/200-d-blue-white.jpg","datePublished":"2025-02-20T07:37:52+00:00","dateModified":"2025-03-11T09:13:22+00:00","breadcrumb":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-200d-blue-white\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-200d-blue-white\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-200d-blue-white\/#primaryimage","url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/200-d-blue-white.jpg","contentUrl":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/02\/200-d-blue-white.jpg","width":1250,"height":1250,"caption":"Blue & White"},{"@type":"BreadcrumbList","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-200d-blue-white\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cwsdelhi.co.in\/naturegold\/"},{"@type":"ListItem","position":2,"name":"NG-200D (Blue &#038; White)"}]},{"@type":"WebSite","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#website","url":"https:\/\/cwsdelhi.co.in\/naturegold\/","name":"Nature Gold","description":"","publisher":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cwsdelhi.co.in\/naturegold\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#organization","name":"Nature Gold","url":"https:\/\/cwsdelhi.co.in\/naturegold\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#\/schema\/logo\/image\/","url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/11\/nature_gold1.png","contentUrl":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/11\/nature_gold1.png","width":546,"height":246,"caption":"Nature Gold"},"image":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool\/2118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool"}],"about":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/types\/tool"}],"version-history":[{"count":1,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool\/2118\/revisions"}],"predecessor-version":[{"id":2123,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool\/2118\/revisions\/2123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/media\/2119"}],"wp:attachment":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/media?parent=2118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/categories?post=2118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}