{"id":1469,"date":"2025-01-21T13:21:24","date_gmt":"2025-01-21T13:21:24","guid":{"rendered":"https:\/\/cwsdelhi.co.in\/naturegold\/?post_type=tool&#038;p=1469"},"modified":"2025-01-31T05:23:18","modified_gmt":"2025-01-31T05:23:18","slug":"ngi-5073-6","status":"publish","type":"tool","link":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ngi-5073-6\/","title":{"rendered":"NGI-5073-6"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1602,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"categories":[14],"class_list":["post-1469","tool","type-tool","status-publish","has-post-thumbnail","hentry","category-hand-pressure-sprayer"],"acf":{"photo_gallery":{"gallery":[[{"id":1917,"title":"NGI-5073-6","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6.jpeg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-150x150.jpeg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-1024x1024.jpeg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-300x300.jpeg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-150x150.jpeg 150w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-768x768.jpeg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-1536x1536.jpeg 1536w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6.jpeg 1600w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-300x300.jpeg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-1024x1024.jpeg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-150x150.jpeg 150w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-768x768.jpeg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-1536x1536.jpeg 1536w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6.jpeg 1600w","media_details":{"width":1600,"height":1600,"sizes":{"medium":{"file":"NGI-5073-6-300x300.jpeg","width":300,"height":300,"mime-type":"image\/jpeg","filesize":10277,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-300x300.jpeg"},"large":{"file":"NGI-5073-6-1024x1024.jpeg","width":1024,"height":1024,"mime-type":"image\/jpeg","filesize":50710,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-1024x1024.jpeg"},"thumbnail":{"file":"NGI-5073-6-150x150.jpeg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":4380,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-150x150.jpeg"},"medium_large":{"file":"NGI-5073-6-768x768.jpeg","width":768,"height":768,"mime-type":"image\/jpeg","filesize":34587,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-768x768.jpeg"},"1536x1536":{"file":"NGI-5073-6-1536x1536.jpeg","width":1536,"height":1536,"mime-type":"image\/jpeg","filesize":89482,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6-1536x1536.jpeg"}}},"alt_text":"","url":"","target":""},{"id":1477,"title":"NG-1-5073-6","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NG-1-5073-6.png","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NG-1-5073-6-150x150.png","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NG-1-5073-6-683x1024.png 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NG-1-5073-6-200x300.png 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NG-1-5073-6-768x1152.png 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NG-1-5073-6.png 1000w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NG-1-5073-6-200x300.png 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NG-1-5073-6-683x1024.png 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NG-1-5073-6-768x1152.png 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NG-1-5073-6.png 1000w","media_details":{"width":1000,"height":1500,"sizes":{"medium":{"file":"NG-1-5073-6-200x300.png","width":200,"height":300,"mime-type":"image\/png","filesize":27160,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NG-1-5073-6-200x300.png"},"large":{"file":"NG-1-5073-6-683x1024.png","width":683,"height":1024,"mime-type":"image\/png","filesize":256466,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NG-1-5073-6-683x1024.png"},"thumbnail":{"file":"NG-1-5073-6-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":15942,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NG-1-5073-6-150x150.png"},"medium_large":{"file":"NG-1-5073-6-768x1152.png","width":768,"height":1152,"mime-type":"image\/png","filesize":322258,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NG-1-5073-6-768x1152.png"}}},"alt_text":"","url":"","target":""},{"id":1476,"title":"DSC_0232","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0232.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0232-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0232-683x1024.jpg 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0232-200x300.jpg 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0232-768x1152.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0232.jpg 1000w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0232-200x300.jpg 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0232-683x1024.jpg 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0232-768x1152.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0232.jpg 1000w","media_details":{"width":1000,"height":1500,"sizes":{"medium":{"file":"DSC_0232-200x300.jpg","width":200,"height":300,"mime-type":"image\/jpeg","filesize":33616,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0232-200x300.jpg"},"large":{"file":"DSC_0232-683x1024.jpg","width":683,"height":1024,"mime-type":"image\/jpeg","filesize":139160,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0232-683x1024.jpg"},"thumbnail":{"file":"DSC_0232-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":22866,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0232-150x150.jpg"},"medium_large":{"file":"DSC_0232-768x1152.jpg","width":768,"height":1152,"mime-type":"image\/jpeg","filesize":161846,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0232-768x1152.jpg"}}},"alt_text":"","url":"","target":""},{"id":1475,"title":"DSC_0231","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0231.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0231-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0231-683x1024.jpg 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0231-200x300.jpg 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0231-768x1152.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0231.jpg 1000w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0231-200x300.jpg 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0231-683x1024.jpg 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0231-768x1152.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0231.jpg 1000w","media_details":{"width":1000,"height":1500,"sizes":{"medium":{"file":"DSC_0231-200x300.jpg","width":200,"height":300,"mime-type":"image\/jpeg","filesize":36225,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0231-200x300.jpg"},"large":{"file":"DSC_0231-683x1024.jpg","width":683,"height":1024,"mime-type":"image\/jpeg","filesize":151850,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0231-683x1024.jpg"},"thumbnail":{"file":"DSC_0231-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":24363,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0231-150x150.jpg"},"medium_large":{"file":"DSC_0231-768x1152.jpg","width":768,"height":1152,"mime-type":"image\/jpeg","filesize":176116,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0231-768x1152.jpg"}}},"alt_text":"","url":"","target":""},{"id":1474,"title":"DSC_0054","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0054.png","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0054-150x150.png","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0054-683x1024.png 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0054-200x300.png 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0054-768x1152.png 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0054.png 1000w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0054-200x300.png 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0054-683x1024.png 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0054-768x1152.png 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0054.png 1000w","media_details":{"width":1000,"height":1500,"sizes":{"medium":{"file":"DSC_0054-200x300.png","width":200,"height":300,"mime-type":"image\/png","filesize":26116,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0054-200x300.png"},"large":{"file":"DSC_0054-683x1024.png","width":683,"height":1024,"mime-type":"image\/png","filesize":264060,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0054-683x1024.png"},"thumbnail":{"file":"DSC_0054-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":15803,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0054-150x150.png"},"medium_large":{"file":"DSC_0054-768x1152.png","width":768,"height":1152,"mime-type":"image\/png","filesize":335104,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0054-768x1152.png"}}},"alt_text":"","url":"","target":""},{"id":1473,"title":"DSC_0041","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0041.png","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0041-150x150.png","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0041-683x1024.png 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0041-200x300.png 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0041-768x1152.png 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0041.png 1000w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0041-200x300.png 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0041-683x1024.png 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0041-768x1152.png 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0041.png 1000w","media_details":{"width":1000,"height":1500,"sizes":{"medium":{"file":"DSC_0041-200x300.png","width":200,"height":300,"mime-type":"image\/png","filesize":30813,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0041-200x300.png"},"large":{"file":"DSC_0041-683x1024.png","width":683,"height":1024,"mime-type":"image\/png","filesize":289483,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0041-683x1024.png"},"thumbnail":{"file":"DSC_0041-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":17564,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0041-150x150.png"},"medium_large":{"file":"DSC_0041-768x1152.png","width":768,"height":1152,"mime-type":"image\/png","filesize":365057,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0041-768x1152.png"}}},"alt_text":"","url":"","target":""},{"id":1472,"title":"DSC_0039","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0039.png","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0039-150x150.png","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0039-683x1024.png 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0039-200x300.png 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0039-768x1152.png 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0039.png 1000w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0039-200x300.png 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0039-683x1024.png 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0039-768x1152.png 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0039.png 1000w","media_details":{"width":1000,"height":1500,"sizes":{"medium":{"file":"DSC_0039-200x300.png","width":200,"height":300,"mime-type":"image\/png","filesize":30633,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0039-200x300.png"},"large":{"file":"DSC_0039-683x1024.png","width":683,"height":1024,"mime-type":"image\/png","filesize":294203,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0039-683x1024.png"},"thumbnail":{"file":"DSC_0039-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":17557,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0039-150x150.png"},"medium_large":{"file":"DSC_0039-768x1152.png","width":768,"height":1152,"mime-type":"image\/png","filesize":370023,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0039-768x1152.png"}}},"alt_text":"","url":"","target":""},{"id":1470,"title":"21","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/21-1.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/21-1-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/21-1.jpg 1000w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/21-1-300x300.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/21-1-150x150.jpg 150w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/21-1-768x768.jpg 768w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/21-1-300x300.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/21-1-150x150.jpg 150w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/21-1-768x768.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/21-1.jpg 1000w","media_details":{"width":1000,"height":1000,"sizes":{"medium":{"file":"21-1-300x300.jpg","width":300,"height":300,"mime-type":"image\/jpeg","filesize":28122,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/21-1-300x300.jpg"},"thumbnail":{"file":"21-1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":19806,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/21-1-150x150.jpg"},"medium_large":{"file":"21-1-768x768.jpg","width":768,"height":768,"mime-type":"image\/jpeg","filesize":63521,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/21-1-768x768.jpg"}}},"alt_text":"","url":"","target":""}]]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NGI-5073-6 - Nature Gold<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ngi-5073-6\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NGI-5073-6 - Nature Gold\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ngi-5073-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Nature Gold\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-31T05:23:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1250\" \/>\n\t<meta property=\"og:image:height\" content=\"1250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ngi-5073-6\\\/\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ngi-5073-6\\\/\",\"name\":\"NGI-5073-6 - Nature Gold\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ngi-5073-6\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ngi-5073-6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/NGI-5073-6.jpg\",\"datePublished\":\"2025-01-21T13:21:24+00:00\",\"dateModified\":\"2025-01-31T05:23:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ngi-5073-6\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ngi-5073-6\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ngi-5073-6\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/NGI-5073-6.jpg\",\"contentUrl\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/NGI-5073-6.jpg\",\"width\":1250,\"height\":1250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ngi-5073-6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NGI-5073-6\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#website\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/\",\"name\":\"Nature Gold\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#organization\",\"name\":\"Nature Gold\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/nature_gold1.png\",\"contentUrl\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/nature_gold1.png\",\"width\":546,\"height\":246,\"caption\":\"Nature Gold\"},\"image\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NGI-5073-6 - Nature Gold","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ngi-5073-6\/","og_locale":"en_US","og_type":"article","og_title":"NGI-5073-6 - Nature Gold","og_url":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ngi-5073-6\/","og_site_name":"Nature Gold","article_modified_time":"2025-01-31T05:23:18+00:00","og_image":[{"width":1250,"height":1250,"url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ngi-5073-6\/","url":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ngi-5073-6\/","name":"NGI-5073-6 - Nature Gold","isPartOf":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ngi-5073-6\/#primaryimage"},"image":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ngi-5073-6\/#primaryimage"},"thumbnailUrl":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6.jpg","datePublished":"2025-01-21T13:21:24+00:00","dateModified":"2025-01-31T05:23:18+00:00","breadcrumb":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ngi-5073-6\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ngi-5073-6\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ngi-5073-6\/#primaryimage","url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6.jpg","contentUrl":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/NGI-5073-6.jpg","width":1250,"height":1250},{"@type":"BreadcrumbList","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ngi-5073-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cwsdelhi.co.in\/naturegold\/"},{"@type":"ListItem","position":2,"name":"NGI-5073-6"}]},{"@type":"WebSite","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#website","url":"https:\/\/cwsdelhi.co.in\/naturegold\/","name":"Nature Gold","description":"","publisher":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cwsdelhi.co.in\/naturegold\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#organization","name":"Nature Gold","url":"https:\/\/cwsdelhi.co.in\/naturegold\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#\/schema\/logo\/image\/","url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/11\/nature_gold1.png","contentUrl":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/11\/nature_gold1.png","width":546,"height":246,"caption":"Nature Gold"},"image":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool\/1469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool"}],"about":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/types\/tool"}],"version-history":[{"count":2,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool\/1469\/revisions"}],"predecessor-version":[{"id":1633,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool\/1469\/revisions\/1633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/media\/1602"}],"wp:attachment":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/media?parent=1469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/categories?post=1469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}