{"id":1292,"date":"2025-01-14T09:55:54","date_gmt":"2025-01-14T09:55:54","guid":{"rendered":"https:\/\/cwsdelhi.co.in\/naturegold\/?post_type=tool&#038;p=1292"},"modified":"2025-01-14T09:55:54","modified_gmt":"2025-01-14T09:55:54","slug":"ng-gp-01","status":"publish","type":"tool","link":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-gp-01\/","title":{"rendered":"NG-GP-01"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1293,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"categories":[6],"class_list":["post-1292","tool","type-tool","status-publish","has-post-thumbnail","hentry","category-pruners"],"acf":{"photo_gallery":{"gallery":[[{"id":1300,"title":"DSC_0047","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0047.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0047-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0047-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0047-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0047-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0047.jpg 1500w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0047-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0047-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0047-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0047.jpg 1500w","media_details":{"width":1500,"height":1000,"sizes":{"medium":{"file":"DSC_0047-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":14125,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0047-300x200.jpg"},"large":{"file":"DSC_0047-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":95406,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0047-1024x683.jpg"},"thumbnail":{"file":"DSC_0047-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6547,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0047-150x150.jpg"},"medium_large":{"file":"DSC_0047-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":60770,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0047-768x512.jpg"}}},"alt_text":"","url":"","target":""},{"id":1299,"title":"DSC_0046","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0046.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0046-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0046-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0046-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0046-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0046.jpg 1500w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0046-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0046-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0046-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0046.jpg 1500w","media_details":{"width":1500,"height":1000,"sizes":{"medium":{"file":"DSC_0046-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":12313,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0046-300x200.jpg"},"large":{"file":"DSC_0046-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":78331,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0046-1024x683.jpg"},"thumbnail":{"file":"DSC_0046-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5703,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0046-150x150.jpg"},"medium_large":{"file":"DSC_0046-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":50256,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0046-768x512.jpg"}}},"alt_text":"","url":"","target":""},{"id":1298,"title":"DSC_0112","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0112.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0112-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0112-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0112-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0112-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0112.jpg 1500w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0112-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0112-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0112-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0112.jpg 1500w","media_details":{"width":1500,"height":1000,"sizes":{"medium":{"file":"DSC_0112-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":4353,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0112-300x200.jpg"},"large":{"file":"DSC_0112-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":26730,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0112-1024x683.jpg"},"thumbnail":{"file":"DSC_0112-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":2830,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0112-150x150.jpg"},"medium_large":{"file":"DSC_0112-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":17128,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0112-768x512.jpg"}}},"alt_text":"","url":"","target":""},{"id":1297,"title":"DSC_0111","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0111.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0111-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0111-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0111-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0111-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0111.jpg 1500w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0111-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0111-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0111-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0111.jpg 1500w","media_details":{"width":1500,"height":1000,"sizes":{"medium":{"file":"DSC_0111-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":4556,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0111-300x200.jpg"},"large":{"file":"DSC_0111-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":28946,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0111-1024x683.jpg"},"thumbnail":{"file":"DSC_0111-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":2956,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0111-150x150.jpg"},"medium_large":{"file":"DSC_0111-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":18470,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0111-768x512.jpg"}}},"alt_text":"","url":"","target":""},{"id":1296,"title":"DSC_0110","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0110.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0110-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0110-683x1024.jpg 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0110-200x300.jpg 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0110-768x1152.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0110.jpg 1000w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0110-200x300.jpg 200w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0110-683x1024.jpg 683w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0110-768x1152.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0110.jpg 1000w","media_details":{"width":1000,"height":1500,"sizes":{"medium":{"file":"DSC_0110-200x300.jpg","width":200,"height":300,"mime-type":"image\/jpeg","filesize":6709,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0110-200x300.jpg"},"large":{"file":"DSC_0110-683x1024.jpg","width":683,"height":1024,"mime-type":"image\/jpeg","filesize":52298,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0110-683x1024.jpg"},"thumbnail":{"file":"DSC_0110-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":3918,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0110-150x150.jpg"},"medium_large":{"file":"DSC_0110-768x1152.jpg","width":768,"height":1152,"mime-type":"image\/jpeg","filesize":62824,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0110-768x1152.jpg"}}},"alt_text":"","url":"","target":""},{"id":1295,"title":"DSC_0051","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0051.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0051-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0051-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0051-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0051-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0051.jpg 1500w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0051-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0051-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0051-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0051.jpg 1500w","media_details":{"width":1500,"height":1000,"sizes":{"medium":{"file":"DSC_0051-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":14525,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0051-300x200.jpg"},"large":{"file":"DSC_0051-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":100919,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0051-1024x683.jpg"},"thumbnail":{"file":"DSC_0051-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6571,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0051-150x150.jpg"},"medium_large":{"file":"DSC_0051-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":64808,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0051-768x512.jpg"}}},"alt_text":"","url":"","target":""},{"id":1294,"title":"DSC_0049","caption":"","full_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0049.jpg","thumbnail_image_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0049-150x150.jpg","large_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0049-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0049-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0049-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0049.jpg 1500w","medium_srcset":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0049-300x200.jpg 300w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0049-1024x683.jpg 1024w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0049-768x512.jpg 768w, https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0049.jpg 1500w","media_details":{"width":1500,"height":1000,"sizes":{"medium":{"file":"DSC_0049-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":13290,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0049-300x200.jpg"},"large":{"file":"DSC_0049-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":81924,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0049-1024x683.jpg"},"thumbnail":{"file":"DSC_0049-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6234,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0049-150x150.jpg"},"medium_large":{"file":"DSC_0049-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":53322,"source_url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/DSC_0049-768x512.jpg"}}},"alt_text":"","url":"","target":""}]]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NG-GP-01 - Nature Gold<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-gp-01\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NG-GP-01 - Nature Gold\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-gp-01\/\" \/>\n<meta property=\"og:site_name\" content=\"Nature Gold\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/tap-tool2.0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1250\" \/>\n\t<meta property=\"og:image:height\" content=\"1250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-gp-01\\\/\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-gp-01\\\/\",\"name\":\"NG-GP-01 - Nature Gold\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-gp-01\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-gp-01\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/tap-tool2.0.jpg\",\"datePublished\":\"2025-01-14T09:55:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-gp-01\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-gp-01\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-gp-01\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/tap-tool2.0.jpg\",\"contentUrl\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/tap-tool2.0.jpg\",\"width\":1250,\"height\":1250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/tool\\\/ng-gp-01\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NG-GP-01\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#website\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/\",\"name\":\"Nature Gold\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#organization\",\"name\":\"Nature Gold\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/nature_gold1.png\",\"contentUrl\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/nature_gold1.png\",\"width\":546,\"height\":246,\"caption\":\"Nature Gold\"},\"image\":{\"@id\":\"https:\\\/\\\/cwsdelhi.co.in\\\/naturegold\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NG-GP-01 - Nature Gold","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-gp-01\/","og_locale":"en_US","og_type":"article","og_title":"NG-GP-01 - Nature Gold","og_url":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-gp-01\/","og_site_name":"Nature Gold","og_image":[{"width":1250,"height":1250,"url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/tap-tool2.0.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-gp-01\/","url":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-gp-01\/","name":"NG-GP-01 - Nature Gold","isPartOf":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-gp-01\/#primaryimage"},"image":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-gp-01\/#primaryimage"},"thumbnailUrl":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/tap-tool2.0.jpg","datePublished":"2025-01-14T09:55:54+00:00","breadcrumb":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-gp-01\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-gp-01\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-gp-01\/#primaryimage","url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/tap-tool2.0.jpg","contentUrl":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2025\/01\/tap-tool2.0.jpg","width":1250,"height":1250},{"@type":"BreadcrumbList","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/tool\/ng-gp-01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cwsdelhi.co.in\/naturegold\/"},{"@type":"ListItem","position":2,"name":"NG-GP-01"}]},{"@type":"WebSite","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#website","url":"https:\/\/cwsdelhi.co.in\/naturegold\/","name":"Nature Gold","description":"","publisher":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cwsdelhi.co.in\/naturegold\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#organization","name":"Nature Gold","url":"https:\/\/cwsdelhi.co.in\/naturegold\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#\/schema\/logo\/image\/","url":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/11\/nature_gold1.png","contentUrl":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-content\/uploads\/2024\/11\/nature_gold1.png","width":546,"height":246,"caption":"Nature Gold"},"image":{"@id":"https:\/\/cwsdelhi.co.in\/naturegold\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool\/1292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool"}],"about":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/types\/tool"}],"version-history":[{"count":1,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool\/1292\/revisions"}],"predecessor-version":[{"id":1301,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/tool\/1292\/revisions\/1301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/media\/1293"}],"wp:attachment":[{"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/media?parent=1292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cwsdelhi.co.in\/naturegold\/wp-json\/wp\/v2\/categories?post=1292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}